{"id":11843,"date":"2020-04-02T15:13:29","date_gmt":"2020-04-02T13:13:29","guid":{"rendered":"https:\/\/solunion.com\/?p=11843"},"modified":"2020-04-02T15:13:29","modified_gmt":"2020-04-02T13:13:29","slug":"colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners","status":"publish","type":"post","link":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/","title":{"rendered":"Colaboramos con Trientrenos para fomentar el bienestar de nuestros Solunioners"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11843\" class=\"elementor elementor-11843\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e983fb3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e983fb3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;a2e018c&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55905ad1\" data-id=\"55905ad1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38c7a047 elementor-widget elementor-widget-text-editor\" data-id=\"38c7a047\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestros Solunioners son el coraz\u00f3n y el motor de la compa\u00f1\u00eda. Por eso, hemos puesto en marcha una iniciativa de deporte y nutrici\u00f3n que, en colaboraci\u00f3n con la plataforma online de entrenamientos Trientrenos, tiene como objetivo fomentar el bienestar y los h\u00e1bitos de vida saludable de nuestras personas a trav\u00e9s del deporte y la nutrici\u00f3n.<\/p><p>Hemos adaptado la iniciativa a las circunstancias extraordinarias derivadas de la situaci\u00f3n actual, de modo que todas las actividades deportivas y charlas nutricionales con los expertos de Trientrenos est\u00e1n pensadas para realizarse en casa. De este modo, disponemos desde la plataforma de un plan personalizado de v\u00eddeos y retos saludables elaborados por Alejandro Santamar\u00eda, triatleta profesional y principal responsable de Trientrenos, adaptados a distintos niveles seg\u00fan el grado de actividad f\u00edsica al que estemos acostumbrados.<\/p><p>Asimismo, adem\u00e1s de las rutinas de ejercicio f\u00edsico, los Solunioners de todos los pa\u00edses tendr\u00e1n la oportunidad de asistir virtualmente a sesiones informativas e instructivas semanales lideradas por un nutricionista especializado de Trientrenos.<\/p><p>\u00a0\u201cEn Solunion estamos plenamente comprometidos con el bienestar de nuestras personas, a\u00fan m\u00e1s si cabe a lo largo de este periodo. Esta iniciativa, en la que nos acompa\u00f1an grandes profesionales del deporte y la nutrici\u00f3n, forma parte de un plan integral construido en torno a la salud, el cuidado y la protecci\u00f3n de todos ellos antes, durante y despu\u00e9s de esta situaci\u00f3n\u201d, se\u00f1ala Ernesto Rodr\u00edguez,\u00a0 nuestro Director Corporativo de Personas y Sostenibilidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nuestros Solunioners son el coraz\u00f3n y el motor de la compa\u00f1\u00eda. Por eso, hemos puesto en marcha una iniciativa de deporte y nutrici\u00f3n que, en colaboraci\u00f3n con la plataforma online de entrenamientos Trientrenos, tiene como objetivo fomentar el bienestar y los h\u00e1bitos de vida saludable de nuestras personas a trav\u00e9s del deporte y la nutrici\u00f3n. [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":11844,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"Product","footnotes":""},"categories":[313],"tags":[],"class_list":["post-11843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personas-y-sostenibilidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colaboramos con Trientrenos para fomentar el bienestar de nuestros Solunioners - Solunion, Credit and Surety insurance<\/title>\n<meta name=\"description\" content=\"Trientrenos es un programa que adapta diferentes pautas de vida saludable a los usuarios. En Solunion, cuidamos el bienestar de nuestras personas...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colaboramos con Trientrenos para fomentar el bienestar de nuestros Solunioners - Solunion, Credit and Surety insurance\" \/>\n<meta property=\"og:description\" content=\"Trientrenos es un programa que adapta diferentes pautas de vida saludable a los usuarios. En Solunion, cuidamos el bienestar de nuestras personas...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/\" \/>\n<meta property=\"og:site_name\" content=\"Solunion, Credit and Surety insurance\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-02T13:13:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/trientrenos-solunion.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Solunion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@carla@showerthinking.com\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solunion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\\\/\"},\"author\":{\"name\":\"Solunion\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\"},\"headline\":\"Colaboramos con Trientrenos para fomentar el bienestar de nuestros Solunioners\",\"datePublished\":\"2020-04-02T13:13:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\\\/\"},\"wordCount\":271,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/trientrenos-solunion.png\",\"articleSection\":[\"Personas y Sostenibilidad\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/solunion.com\\\/en\\\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\\\/\",\"name\":\"Colaboramos con Trientrenos para fomentar el bienestar de nuestros Solunioners - Solunion, Credit and Surety insurance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/trientrenos-solunion.png\",\"datePublished\":\"2020-04-02T13:13:29+00:00\",\"description\":\"Trientrenos es un programa que adapta diferentes pautas de vida saludable a los usuarios. En Solunion, cuidamos el bienestar de nuestras personas...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solunion.com\\\/en\\\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/trientrenos-solunion.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/trientrenos-solunion.png\",\"width\":900,\"height\":508},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solunion.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colaboramos con Trientrenos para fomentar el bienestar de nuestros Solunioners\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"name\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"description\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"alternateName\":\"Solunion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solunion.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\",\"name\":\"Solunion\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"width\":350,\"height\":96,\"caption\":\"Solunion\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\",\"name\":\"Solunion\",\"description\":\"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/carla@showerthinking.com\"]},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colaboramos con Trientrenos para fomentar el bienestar de nuestros Solunioners - Solunion, Credit and Surety insurance","description":"Trientrenos es un programa que adapta diferentes pautas de vida saludable a los usuarios. En Solunion, cuidamos el bienestar de nuestras personas...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/","og_locale":"en_US","og_type":"article","og_title":"Colaboramos con Trientrenos para fomentar el bienestar de nuestros Solunioners - Solunion, Credit and Surety insurance","og_description":"Trientrenos es un programa que adapta diferentes pautas de vida saludable a los usuarios. En Solunion, cuidamos el bienestar de nuestras personas...","og_url":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/","og_site_name":"Solunion, Credit and Surety insurance","article_published_time":"2020-04-02T13:13:29+00:00","og_image":[{"width":900,"height":508,"url":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/trientrenos-solunion.png","type":"image\/png"}],"author":"Solunion","twitter_card":"summary_large_image","twitter_creator":"@carla@showerthinking.com","twitter_misc":{"Written by":"Solunion","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/#article","isPartOf":{"@id":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/"},"author":{"name":"Solunion","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366"},"headline":"Colaboramos con Trientrenos para fomentar el bienestar de nuestros Solunioners","datePublished":"2020-04-02T13:13:29+00:00","mainEntityOfPage":{"@id":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/"},"wordCount":271,"commentCount":0,"publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"image":{"@id":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/trientrenos-solunion.png","articleSection":["Personas y Sostenibilidad"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/","url":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/","name":"Colaboramos con Trientrenos para fomentar el bienestar de nuestros Solunioners - Solunion, Credit and Surety insurance","isPartOf":{"@id":"https:\/\/solunion.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/#primaryimage"},"image":{"@id":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/trientrenos-solunion.png","datePublished":"2020-04-02T13:13:29+00:00","description":"Trientrenos es un programa que adapta diferentes pautas de vida saludable a los usuarios. En Solunion, cuidamos el bienestar de nuestras personas...","breadcrumb":{"@id":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/#primaryimage","url":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/trientrenos-solunion.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/trientrenos-solunion.png","width":900,"height":508},{"@type":"BreadcrumbList","@id":"https:\/\/solunion.com\/en\/colaboramos-con-trientrenos-para-fomentar-el-bienestar-de-nuestros-solunioners\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solunion.com\/en\/"},{"@type":"ListItem","position":2,"name":"Colaboramos con Trientrenos para fomentar el bienestar de nuestros Solunioners"}]},{"@type":"WebSite","@id":"https:\/\/solunion.com\/en\/#website","url":"https:\/\/solunion.com\/en\/","name":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","description":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"alternateName":"Solunion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solunion.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/solunion.com\/en\/#organization","name":"Solunion","url":"https:\/\/solunion.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","width":350,"height":96,"caption":"Solunion"},"image":{"@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366","name":"Solunion","description":"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.","sameAs":["https:\/\/x.com\/carla@showerthinking.com"]},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/11843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/comments?post=11843"}],"version-history":[{"count":0,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/11843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media\/11844"}],"wp:attachment":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media?parent=11843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/categories?post=11843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/tags?post=11843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}