{"id":11904,"date":"2020-04-16T19:04:23","date_gmt":"2020-04-16T17:04:23","guid":{"rendered":"https:\/\/solunion.com\/?p=11904"},"modified":"2020-04-20T12:17:21","modified_gmt":"2020-04-20T10:17:21","slug":"salir-del-bloqueo-del-coronavirus","status":"publish","type":"post","link":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/","title":{"rendered":"Dejar atr\u00e1s el confinamiento: un cuento de cuatro historias"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11904\" class=\"elementor elementor-11904\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-410d91 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"410d91\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;a2e018c&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad91ca3\" data-id=\"ad91ca3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28ba3dac elementor-widget elementor-widget-text-editor\" data-id=\"28ba3dac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Este nuevo informe de Euler Hermes, uno de nuestros accionistas, junto con MAPFRE,\u00a0 analiza la posible salida progresiva del bloqueo generado por la crisis del coronavirus.\u00a0<\/p><p>No todos los pa\u00edses est\u00e1n en el mismo barco. Cada uno enfrenta riesgos diferentes en <strong>v\u00edsperas del desconfinamiento.<\/strong> Comenzando con las condiciones iniciales, es evidente, a partir de los datos epidemiol\u00f3gicos, que pocos pa\u00edses est\u00e1n en condiciones de comenzar a levantar las medidas de aislamiento.<\/p><p>Sin embargo, a muchos les gustar\u00eda comenzar a<strong> relajar las restricciones<\/strong> lo antes posible para apoyar sus econom\u00edas. Para comprender las posibles estrategias de salida y los riesgos asociados con ellas, el informe agrupa a los pa\u00edses en dos dimensiones que analizan sus condiciones iniciales, antes de levantar sus bloqueos: (1) su situaci\u00f3n en materia sanitaria y (2) la vulnerabilidad econ\u00f3mica asociada al confinamiento.<\/p><p>El an\u00e1lisis de Euler Hermes clasifica los pa\u00edses en cuatro grupos: el <strong>primero<\/strong> comprende los <strong>pa\u00edses emergentes vulnerables<\/strong> que a\u00fan no est\u00e1n preparados para el desconfinamiento; el <strong>segundo, los <em>early birds<\/em><\/strong>, est\u00e1n cerca de haber vencido al virus, habiendo aumentado tanto su capacidad para realizar pruebas y la capacidad m\u00e9dica. El <strong>tercer grupo<\/strong> comprende los <strong>pa\u00edses fronterizos<\/strong>, en los que, o bien se ha avanzado en la detenci\u00f3n de la propagaci\u00f3n del virus o la capacidad m\u00e9dica y de realizaci\u00f3n de pruebas ha superado a sus pares. Por \u00faltimo, el c<strong>uarto grupo comprende los pa\u00edses que siguen luchando contra la epidemia <\/strong>pero que han demostrado ser vulnerables a un confinamiento prolongado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b5f1135 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b5f1135\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;fada2ab&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-47ac1b\" data-id=\"47ac1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b11ded4 elementor-widget elementor-widget-text-editor\" data-id=\"2b11ded4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Accede al informe completo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7a393dfd\" data-id=\"7a393dfd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d29018d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4d29018d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.eulerhermes.com\/en_global\/economic-research\/news\/covid19-lifting-the-lockdown.html\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-chart-bar\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Informe original<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Este nuevo informe de Euler Hermes, uno de nuestros accionistas, junto con MAPFRE,\u00a0 analiza la posible salida progresiva del bloqueo generado por la crisis del coronavirus.\u00a0 No todos los pa\u00edses est\u00e1n en el mismo barco. Cada uno enfrenta riesgos diferentes en v\u00edsperas del desconfinamiento. Comenzando con las condiciones iniciales, es evidente, a partir de los [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":11905,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"Product","footnotes":""},"categories":[301],"tags":[424,422,423],"class_list":["post-11904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escenario-macroeconomico","tag-crisis-coronavirus","tag-desconfinamiento","tag-levantamiento-de-las-medidas-de-aislamiento"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dejar atr\u00e1s el confinamiento: un cuento de cuatro historias - Solunion, Credit and Surety insurance<\/title>\n<meta name=\"description\" content=\"La salida del bloqueo derivado de la imposici\u00f3n de medidas de aislamiento para luchar frente a la expansi\u00f3n del coronavirus, ser\u00e1 diferente para cada pa\u00eds\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dejar atr\u00e1s el confinamiento: un cuento de cuatro historias - Solunion, Credit and Surety insurance\" \/>\n<meta property=\"og:description\" content=\"La salida del bloqueo derivado de la imposici\u00f3n de medidas de aislamiento para luchar frente a la expansi\u00f3n del coronavirus, ser\u00e1 diferente para cada pa\u00eds\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"Solunion, Credit and Surety insurance\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-16T17:04:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-20T10:17:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/salida-confinamiento-solunion.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Solunion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@carla@showerthinking.com\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solunion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/salir-del-bloqueo-del-coronavirus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/salir-del-bloqueo-del-coronavirus\\\/\"},\"author\":{\"name\":\"Solunion\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\"},\"headline\":\"Dejar atr\u00e1s el confinamiento: un cuento de cuatro historias\",\"datePublished\":\"2020-04-16T17:04:23+00:00\",\"dateModified\":\"2020-04-20T10:17:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/salir-del-bloqueo-del-coronavirus\\\/\"},\"wordCount\":284,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/salir-del-bloqueo-del-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/salida-confinamiento-solunion.png\",\"keywords\":[\"crisis coronavirus\",\"desconfinamiento\",\"levantamiento de las medidas de aislamiento\"],\"articleSection\":[\"Escenario macroecon\u00f3mico\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/solunion.com\\\/en\\\/salir-del-bloqueo-del-coronavirus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/salir-del-bloqueo-del-coronavirus\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/salir-del-bloqueo-del-coronavirus\\\/\",\"name\":\"Dejar atr\u00e1s el confinamiento: un cuento de cuatro historias - Solunion, Credit and Surety insurance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/salir-del-bloqueo-del-coronavirus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/salir-del-bloqueo-del-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/salida-confinamiento-solunion.png\",\"datePublished\":\"2020-04-16T17:04:23+00:00\",\"dateModified\":\"2020-04-20T10:17:21+00:00\",\"description\":\"La salida del bloqueo derivado de la imposici\u00f3n de medidas de aislamiento para luchar frente a la expansi\u00f3n del coronavirus, ser\u00e1 diferente para cada pa\u00eds\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/salir-del-bloqueo-del-coronavirus\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solunion.com\\\/en\\\/salir-del-bloqueo-del-coronavirus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/salir-del-bloqueo-del-coronavirus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/salida-confinamiento-solunion.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/salida-confinamiento-solunion.png\",\"width\":900,\"height\":508},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/salir-del-bloqueo-del-coronavirus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solunion.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dejar atr\u00e1s el confinamiento: un cuento de cuatro historias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"name\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"description\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"alternateName\":\"Solunion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solunion.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\",\"name\":\"Solunion\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"width\":350,\"height\":96,\"caption\":\"Solunion\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\",\"name\":\"Solunion\",\"description\":\"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/carla@showerthinking.com\"]},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dejar atr\u00e1s el confinamiento: un cuento de cuatro historias - Solunion, Credit and Surety insurance","description":"La salida del bloqueo derivado de la imposici\u00f3n de medidas de aislamiento para luchar frente a la expansi\u00f3n del coronavirus, ser\u00e1 diferente para cada pa\u00eds","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/","og_locale":"en_US","og_type":"article","og_title":"Dejar atr\u00e1s el confinamiento: un cuento de cuatro historias - Solunion, Credit and Surety insurance","og_description":"La salida del bloqueo derivado de la imposici\u00f3n de medidas de aislamiento para luchar frente a la expansi\u00f3n del coronavirus, ser\u00e1 diferente para cada pa\u00eds","og_url":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/","og_site_name":"Solunion, Credit and Surety insurance","article_published_time":"2020-04-16T17:04:23+00:00","article_modified_time":"2020-04-20T10:17:21+00:00","og_image":[{"width":900,"height":508,"url":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/salida-confinamiento-solunion.png","type":"image\/png"}],"author":"Solunion","twitter_card":"summary_large_image","twitter_creator":"@carla@showerthinking.com","twitter_misc":{"Written by":"Solunion","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/#article","isPartOf":{"@id":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/"},"author":{"name":"Solunion","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366"},"headline":"Dejar atr\u00e1s el confinamiento: un cuento de cuatro historias","datePublished":"2020-04-16T17:04:23+00:00","dateModified":"2020-04-20T10:17:21+00:00","mainEntityOfPage":{"@id":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/"},"wordCount":284,"commentCount":0,"publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"image":{"@id":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/salida-confinamiento-solunion.png","keywords":["crisis coronavirus","desconfinamiento","levantamiento de las medidas de aislamiento"],"articleSection":["Escenario macroecon\u00f3mico"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/","url":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/","name":"Dejar atr\u00e1s el confinamiento: un cuento de cuatro historias - Solunion, Credit and Surety insurance","isPartOf":{"@id":"https:\/\/solunion.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/salida-confinamiento-solunion.png","datePublished":"2020-04-16T17:04:23+00:00","dateModified":"2020-04-20T10:17:21+00:00","description":"La salida del bloqueo derivado de la imposici\u00f3n de medidas de aislamiento para luchar frente a la expansi\u00f3n del coronavirus, ser\u00e1 diferente para cada pa\u00eds","breadcrumb":{"@id":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/#primaryimage","url":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/salida-confinamiento-solunion.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/salida-confinamiento-solunion.png","width":900,"height":508},{"@type":"BreadcrumbList","@id":"https:\/\/solunion.com\/en\/salir-del-bloqueo-del-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solunion.com\/en\/"},{"@type":"ListItem","position":2,"name":"Dejar atr\u00e1s el confinamiento: un cuento de cuatro historias"}]},{"@type":"WebSite","@id":"https:\/\/solunion.com\/en\/#website","url":"https:\/\/solunion.com\/en\/","name":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","description":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"alternateName":"Solunion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solunion.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/solunion.com\/en\/#organization","name":"Solunion","url":"https:\/\/solunion.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","width":350,"height":96,"caption":"Solunion"},"image":{"@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366","name":"Solunion","description":"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.","sameAs":["https:\/\/x.com\/carla@showerthinking.com"]},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/11904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/comments?post=11904"}],"version-history":[{"count":0,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/11904\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media\/11905"}],"wp:attachment":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media?parent=11904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/categories?post=11904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/tags?post=11904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}