{"id":11907,"date":"2020-04-17T12:45:32","date_gmt":"2020-04-17T10:45:32","guid":{"rendered":"https:\/\/solunion.com\/?p=11907"},"modified":"2020-09-08T08:58:26","modified_gmt":"2020-09-08T06:58:26","slug":"impacto-del-covid-en-estados-unidos","status":"publish","type":"post","link":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/","title":{"rendered":"El Covid-19 elevar\u00eda la tasa de delincuencia de Estados Unidos un 6,5% y las insolvencias, un 25% en 2020"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11907\" class=\"elementor elementor-11907\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f1c263e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f1c263e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;a2e018c&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c0072e3\" data-id=\"1c0072e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-490f6055 elementor-widget elementor-widget-text-editor\" data-id=\"490f6055\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Compartimos las conclusiones del informe m\u00e1s reciente de Euler Hermes, uno de nuestros accionistas, sobre el <strong>impacto del Covid-19 en las empresas americanas<\/strong>: \u00a0\u2018<em>Covid-19 to increase U.S. delinquency rate by 6.5% and insolvencies by 25% in 2020\u2019<\/em>.<\/p><ul><li><strong>El mayor impacto en la econom\u00eda de Estados Unidos desde 1947.<\/strong> Euler Hermes prev\u00e9 que la contracci\u00f3n de la actividad alcance en el segundo trimestre de 2020 el -30% intertrimestral, lo que representa el doble de la recesi\u00f3n acumulada de 2008-2009.<\/li><li><strong>Una recuperaci\u00f3n en forma de U sigue siendo el escenario principal.<\/strong> El tama\u00f1o y el dise\u00f1o de las medidas de apoyo monetario sugieren que la recuperaci\u00f3n comenzar\u00e1 a partir del tercer trimestre de 2020 y cobrar\u00e1 fuerza en el cuarto trimestre de 2020, lo que permitir\u00e1 un repunte del crecimiento del 3,3% anual en 2021. No obstante, este repunte tendr\u00e1 un coste en t\u00e9rminos de d\u00e9ficit, que se espera sea del 9,6% del PIB en 2020 y del 8,5% del PIB en 2021. Euler Hermes sigue apostando por un escenario en forma de L, que representa una p\u00e9rdida acumulada en t\u00e9rminos de valor a\u00f1adido de 5,5 billones de d\u00f3lares en un horizonte de cuatro a\u00f1os; en lugar de \u00a0los 1,9 billones de d\u00f3lares de nuestro principal supuesto.<\/li><li><strong>Es probable que la tasa de morosidad (pr\u00e9stamos con un retraso de m\u00e1s de 30 d\u00edas) de las empresas estadounidenses en los pr\u00e9stamos comerciales e industriales, alcance un m\u00e1ximo hist\u00f3rico del 6,5% a finales de a\u00f1o, <\/strong>el m\u00e1s alto desde 1992. Sin embargo, el tama\u00f1o y la estructura del est\u00edmulo (equivalente a un vasto sistema de garant\u00edas de cr\u00e9dito) y la liquidez de las empresas estadounidenses permitir\u00e1n una menor progresi\u00f3n de las insolvencias en comparaci\u00f3n con la crisis de las hipotecas <em>subprime<\/em> (esperamos un aumento del 25% de las insolvencias en 2020 frente al 47% en 2008-2009).<\/li><\/ul><ul><li><strong>Las empresas estadounidenses de los sectores mayorista y minorista son las que corren mayor riesgo por la pausa en las ventas, ya que antes de la crisis ten\u00edan, de promedio, menos de un mes de volumen de negocios disponible en efectivo.<\/strong> En las actividades manufactureras, los sectores m\u00e1s expuestos son las industrias del petr\u00f3leo y el carb\u00f3n (18 d\u00edas de facturaci\u00f3n disponible en efectivo), los alimentos (40 d\u00edas), los textiles (44 d\u00edas) y la industria papelera (46 d\u00edas).\u00a0<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-18d0004 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18d0004\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;fada2ab&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3ee45279\" data-id=\"3ee45279\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66713577 elementor-widget elementor-widget-text-editor\" data-id=\"66713577\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Accede al informe completo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-61fee3c1\" data-id=\"61fee3c1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-162942d6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"162942d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.eulerhermes.com\/en_global\/economic-research\/news\/covid19-to-increase-us-delinquencies-insolvencies.html\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-chart-bar\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Informe original<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Compartimos las conclusiones del informe m\u00e1s reciente de Euler Hermes, uno de nuestros accionistas, sobre el impacto del Covid-19 en las empresas americanas: \u00a0\u2018Covid-19 to increase U.S. delinquency rate by 6.5% and insolvencies by 25% in 2020\u2019. El mayor impacto en la econom\u00eda de Estados Unidos desde 1947. Euler Hermes prev\u00e9 que la contracci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":11910,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"Product","footnotes":""},"categories":[301],"tags":[],"class_list":["post-11907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-escenario-macroeconomico"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Covid-19 elevar\u00eda la tasa de delincuencia de Estados Unidos un 6,5% y las insolvencias, un 25% en 2020 - Solunion, Credit and Surety insurance<\/title>\n<meta name=\"description\" content=\"El impacto del Covid-19 en Estados Unidos podr\u00eda disparar las insolvencias un 25% y el \u00edndice de delincuencia un 6,5%, seg\u00fan el \u00faltimo informe\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Covid-19 elevar\u00eda la tasa de delincuencia de Estados Unidos un 6,5% y las insolvencias, un 25% en 2020 - Solunion, Credit and Surety insurance\" \/>\n<meta property=\"og:description\" content=\"El impacto del Covid-19 en Estados Unidos podr\u00eda disparar las insolvencias un 25% y el \u00edndice de delincuencia un 6,5%, seg\u00fan el \u00faltimo informe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/\" \/>\n<meta property=\"og:site_name\" content=\"Solunion, Credit and Surety insurance\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-17T10:45:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-08T06:58:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/estados-unidos-covid-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Solunion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@carla@showerthinking.com\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solunion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/impacto-del-covid-en-estados-unidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/impacto-del-covid-en-estados-unidos\\\/\"},\"author\":{\"name\":\"Solunion\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\"},\"headline\":\"El Covid-19 elevar\u00eda la tasa de delincuencia de Estados Unidos un 6,5% y las insolvencias, un 25% en 2020\",\"datePublished\":\"2020-04-17T10:45:32+00:00\",\"dateModified\":\"2020-09-08T06:58:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/impacto-del-covid-en-estados-unidos\\\/\"},\"wordCount\":419,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/impacto-del-covid-en-estados-unidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/estados-unidos-covid-1.png\",\"articleSection\":[\"Escenario macroecon\u00f3mico\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/solunion.com\\\/en\\\/impacto-del-covid-en-estados-unidos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/impacto-del-covid-en-estados-unidos\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/impacto-del-covid-en-estados-unidos\\\/\",\"name\":\"El Covid-19 elevar\u00eda la tasa de delincuencia de Estados Unidos un 6,5% y las insolvencias, un 25% en 2020 - Solunion, Credit and Surety insurance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/impacto-del-covid-en-estados-unidos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/impacto-del-covid-en-estados-unidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/estados-unidos-covid-1.png\",\"datePublished\":\"2020-04-17T10:45:32+00:00\",\"dateModified\":\"2020-09-08T06:58:26+00:00\",\"description\":\"El impacto del Covid-19 en Estados Unidos podr\u00eda disparar las insolvencias un 25% y el \u00edndice de delincuencia un 6,5%, seg\u00fan el \u00faltimo informe\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/impacto-del-covid-en-estados-unidos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solunion.com\\\/en\\\/impacto-del-covid-en-estados-unidos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/impacto-del-covid-en-estados-unidos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/estados-unidos-covid-1.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/estados-unidos-covid-1.png\",\"width\":900,\"height\":508},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/impacto-del-covid-en-estados-unidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solunion.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Covid-19 elevar\u00eda la tasa de delincuencia de Estados Unidos un 6,5% y las insolvencias, un 25% en 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"name\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"description\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"alternateName\":\"Solunion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solunion.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\",\"name\":\"Solunion\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"width\":350,\"height\":96,\"caption\":\"Solunion\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\",\"name\":\"Solunion\",\"description\":\"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/carla@showerthinking.com\"]},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Covid-19 elevar\u00eda la tasa de delincuencia de Estados Unidos un 6,5% y las insolvencias, un 25% en 2020 - Solunion, Credit and Surety insurance","description":"El impacto del Covid-19 en Estados Unidos podr\u00eda disparar las insolvencias un 25% y el \u00edndice de delincuencia un 6,5%, seg\u00fan el \u00faltimo informe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/","og_locale":"en_US","og_type":"article","og_title":"El Covid-19 elevar\u00eda la tasa de delincuencia de Estados Unidos un 6,5% y las insolvencias, un 25% en 2020 - Solunion, Credit and Surety insurance","og_description":"El impacto del Covid-19 en Estados Unidos podr\u00eda disparar las insolvencias un 25% y el \u00edndice de delincuencia un 6,5%, seg\u00fan el \u00faltimo informe","og_url":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/","og_site_name":"Solunion, Credit and Surety insurance","article_published_time":"2020-04-17T10:45:32+00:00","article_modified_time":"2020-09-08T06:58:26+00:00","og_image":[{"width":900,"height":508,"url":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/estados-unidos-covid-1.png","type":"image\/png"}],"author":"Solunion","twitter_card":"summary_large_image","twitter_creator":"@carla@showerthinking.com","twitter_misc":{"Written by":"Solunion","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/#article","isPartOf":{"@id":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/"},"author":{"name":"Solunion","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366"},"headline":"El Covid-19 elevar\u00eda la tasa de delincuencia de Estados Unidos un 6,5% y las insolvencias, un 25% en 2020","datePublished":"2020-04-17T10:45:32+00:00","dateModified":"2020-09-08T06:58:26+00:00","mainEntityOfPage":{"@id":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/"},"wordCount":419,"commentCount":0,"publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"image":{"@id":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/estados-unidos-covid-1.png","articleSection":["Escenario macroecon\u00f3mico"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/","url":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/","name":"El Covid-19 elevar\u00eda la tasa de delincuencia de Estados Unidos un 6,5% y las insolvencias, un 25% en 2020 - Solunion, Credit and Surety insurance","isPartOf":{"@id":"https:\/\/solunion.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/#primaryimage"},"image":{"@id":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/estados-unidos-covid-1.png","datePublished":"2020-04-17T10:45:32+00:00","dateModified":"2020-09-08T06:58:26+00:00","description":"El impacto del Covid-19 en Estados Unidos podr\u00eda disparar las insolvencias un 25% y el \u00edndice de delincuencia un 6,5%, seg\u00fan el \u00faltimo informe","breadcrumb":{"@id":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/#primaryimage","url":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/estados-unidos-covid-1.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2020\/04\/estados-unidos-covid-1.png","width":900,"height":508},{"@type":"BreadcrumbList","@id":"https:\/\/solunion.com\/en\/impacto-del-covid-en-estados-unidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solunion.com\/en\/"},{"@type":"ListItem","position":2,"name":"El Covid-19 elevar\u00eda la tasa de delincuencia de Estados Unidos un 6,5% y las insolvencias, un 25% en 2020"}]},{"@type":"WebSite","@id":"https:\/\/solunion.com\/en\/#website","url":"https:\/\/solunion.com\/en\/","name":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","description":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"alternateName":"Solunion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solunion.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/solunion.com\/en\/#organization","name":"Solunion","url":"https:\/\/solunion.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","width":350,"height":96,"caption":"Solunion"},"image":{"@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366","name":"Solunion","description":"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.","sameAs":["https:\/\/x.com\/carla@showerthinking.com"]},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/11907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/comments?post=11907"}],"version-history":[{"count":0,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/11907\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media\/11910"}],"wp:attachment":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media?parent=11907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/categories?post=11907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/tags?post=11907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}