{"id":12519,"date":"2021-03-08T09:03:00","date_gmt":"2021-03-08T08:03:00","guid":{"rendered":"https:\/\/solunion.com\/?p=12519"},"modified":"2021-03-08T09:04:27","modified_gmt":"2021-03-08T08:04:27","slug":"orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad","status":"publish","type":"post","link":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/","title":{"rendered":"\u201cOrgullos@s de nuestro color\u201d, Solunioners contra la desigualdad"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12519\" class=\"elementor elementor-12519\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5eb0c67f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5eb0c67f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;a2e018c&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50171603\" data-id=\"50171603\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75217c85 elementor-widget elementor-widget-text-editor\" data-id=\"75217c85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hoy celebramos el <strong>D\u00eda Internacional de la Mujer<\/strong><strong>, <\/strong>y no podemos hacerlo m\u00e1s orgullos@s de nuestro color: \u00a1el morado!<\/p>\n<p>Este a\u00f1o nos unimos a la campa\u00f1a <a href=\"https:\/\/www.internationalwomensday.com\/theme\">#ChooseToChallenge<\/a>, puesta en marcha por la organizaci\u00f3n oficial del International Women\u2019s Day en 2021, <strong>que est\u00e1 muy en l\u00ednea<\/strong> <strong>&nbsp;con nuestra personalidad: es audaz, valiente y comprometida, como somos los <\/strong><strong>S<\/strong><strong>olunioners<\/strong>.<\/p><p>A lo largo de este mes de marzo, compartiremos nuestras im\u00e1genes por la igualdad en nuestro perfil de Instagram.&nbsp;<\/p>\n<p>Porque el 8 de marzo no es solo un d\u00eda para celebrar, sino una <strong>oportunidad para seguir desafiando <\/strong>los prejuicios y la desigualdad de g\u00e9nero en todo el mundo.&nbsp;<\/p><p><br><\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61de693 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61de693\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;8c1b66b&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-607bb71\" data-id=\"607bb71\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Hoy celebramos el D\u00eda Internacional de la Mujer, y no podemos hacerlo m\u00e1s orgullos@s de nuestro color: \u00a1el morado! Este a\u00f1o nos unimos a la campa\u00f1a #ChooseToChallenge, puesta en marcha por la organizaci\u00f3n oficial del International Women\u2019s Day en 2021, que est\u00e1 muy en l\u00ednea &nbsp;con nuestra personalidad: es audaz, valiente y comprometida, como somos [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":12520,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[307],"tags":[],"class_list":["post-12519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asi-somos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cOrgullos@s de nuestro color\u201d, Solunioners contra la desigualdad - Solunion, Credit and Surety insurance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cOrgullos@s de nuestro color\u201d, Solunioners contra la desigualdad - Solunion, Credit and Surety insurance\" \/>\n<meta property=\"og:description\" content=\"Hoy celebramos el D\u00eda Internacional de la Mujer, y no podemos hacerlo m\u00e1s orgullos@s de nuestro color: \u00a1el morado! Este a\u00f1o nos unimos a la campa\u00f1a #ChooseToChallenge, puesta en marcha por la organizaci\u00f3n oficial del International Women\u2019s Day en 2021, que est\u00e1 muy en l\u00ednea &nbsp;con nuestra personalidad: es audaz, valiente y comprometida, como somos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/\" \/>\n<meta property=\"og:site_name\" content=\"Solunion, Credit and Surety insurance\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-08T08:03:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-08T08:04:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/8-m-2021-solunion-web-1024x578.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Solunion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@carla@showerthinking.com\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solunion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\\\/\"},\"author\":{\"name\":\"Solunion\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\"},\"headline\":\"\u201cOrgullos@s de nuestro color\u201d, Solunioners contra la desigualdad\",\"datePublished\":\"2021-03-08T08:03:00+00:00\",\"dateModified\":\"2021-03-08T08:04:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\\\/\"},\"wordCount\":127,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/8-m-2021-solunion-web.png\",\"articleSection\":[\"As\u00ed somos\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/solunion.com\\\/en\\\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\\\/\",\"name\":\"\u201cOrgullos@s de nuestro color\u201d, Solunioners contra la desigualdad - Solunion, Credit and Surety insurance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/8-m-2021-solunion-web.png\",\"datePublished\":\"2021-03-08T08:03:00+00:00\",\"dateModified\":\"2021-03-08T08:04:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solunion.com\\\/en\\\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/8-m-2021-solunion-web.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/8-m-2021-solunion-web.png\",\"width\":1961,\"height\":1107,\"caption\":\"mujeres y hombres de Solunion con la pose #ChooseToChallenge\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solunion.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cOrgullos@s de nuestro color\u201d, Solunioners contra la desigualdad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"name\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"description\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"alternateName\":\"Solunion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solunion.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\",\"name\":\"Solunion\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"width\":350,\"height\":96,\"caption\":\"Solunion\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\",\"name\":\"Solunion\",\"description\":\"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/carla@showerthinking.com\"]},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cOrgullos@s de nuestro color\u201d, Solunioners contra la desigualdad - Solunion, Credit and Surety insurance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/","og_locale":"en_US","og_type":"article","og_title":"\u201cOrgullos@s de nuestro color\u201d, Solunioners contra la desigualdad - Solunion, Credit and Surety insurance","og_description":"Hoy celebramos el D\u00eda Internacional de la Mujer, y no podemos hacerlo m\u00e1s orgullos@s de nuestro color: \u00a1el morado! Este a\u00f1o nos unimos a la campa\u00f1a #ChooseToChallenge, puesta en marcha por la organizaci\u00f3n oficial del International Women\u2019s Day en 2021, que est\u00e1 muy en l\u00ednea &nbsp;con nuestra personalidad: es audaz, valiente y comprometida, como somos [&hellip;]","og_url":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/","og_site_name":"Solunion, Credit and Surety insurance","article_published_time":"2021-03-08T08:03:00+00:00","article_modified_time":"2021-03-08T08:04:27+00:00","og_image":[{"width":1024,"height":578,"url":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/8-m-2021-solunion-web-1024x578.png","type":"image\/png"}],"author":"Solunion","twitter_card":"summary_large_image","twitter_creator":"@carla@showerthinking.com","twitter_misc":{"Written by":"Solunion","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/#article","isPartOf":{"@id":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/"},"author":{"name":"Solunion","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366"},"headline":"\u201cOrgullos@s de nuestro color\u201d, Solunioners contra la desigualdad","datePublished":"2021-03-08T08:03:00+00:00","dateModified":"2021-03-08T08:04:27+00:00","mainEntityOfPage":{"@id":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/"},"wordCount":127,"commentCount":0,"publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"image":{"@id":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/8-m-2021-solunion-web.png","articleSection":["As\u00ed somos"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/","url":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/","name":"\u201cOrgullos@s de nuestro color\u201d, Solunioners contra la desigualdad - Solunion, Credit and Surety insurance","isPartOf":{"@id":"https:\/\/solunion.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/#primaryimage"},"image":{"@id":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/8-m-2021-solunion-web.png","datePublished":"2021-03-08T08:03:00+00:00","dateModified":"2021-03-08T08:04:27+00:00","breadcrumb":{"@id":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/#primaryimage","url":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/8-m-2021-solunion-web.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/8-m-2021-solunion-web.png","width":1961,"height":1107,"caption":"mujeres y hombres de Solunion con la pose #ChooseToChallenge"},{"@type":"BreadcrumbList","@id":"https:\/\/solunion.com\/en\/orgulloss-de-nuestro-color-solunioners-contra-la-desigualdad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solunion.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u201cOrgullos@s de nuestro color\u201d, Solunioners contra la desigualdad"}]},{"@type":"WebSite","@id":"https:\/\/solunion.com\/en\/#website","url":"https:\/\/solunion.com\/en\/","name":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","description":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"alternateName":"Solunion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solunion.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/solunion.com\/en\/#organization","name":"Solunion","url":"https:\/\/solunion.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","width":350,"height":96,"caption":"Solunion"},"image":{"@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366","name":"Solunion","description":"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.","sameAs":["https:\/\/x.com\/carla@showerthinking.com"]},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/12519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/comments?post=12519"}],"version-history":[{"count":0,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/12519\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media\/12520"}],"wp:attachment":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media?parent=12519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/categories?post=12519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/tags?post=12519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}