{"id":12551,"date":"2021-03-22T10:55:48","date_gmt":"2021-03-22T09:55:48","guid":{"rendered":"https:\/\/solunion.com\/?p=12551"},"modified":"2021-03-22T12:57:06","modified_gmt":"2021-03-22T11:57:06","slug":"3-estrategias-para-mitigar-el-riesgo-de-impago","status":"publish","type":"post","link":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/","title":{"rendered":"3 estrategias para mitigar el riesgo de impago"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12551\" class=\"elementor elementor-12551\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61ac5db4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61ac5db4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;a2e018c&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-678e2801\" data-id=\"678e2801\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5467f103 elementor-widget elementor-widget-text-editor\" data-id=\"5467f103\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Como probablemente estar\u00edan de acuerdo la mayor\u00eda de los directores financieros, una funci\u00f3n financiera eficiente y sin fricciones se basa en una combinaci\u00f3n de m\u00faltiples factores, que incluyen liderazgo, tecnolog\u00eda, procesos, talento, experiencia y comunicaci\u00f3n. Operar a un nivel \u00f3ptimo significa que cuando surgen desaf\u00edos, la funci\u00f3n financiera tiene m\u00e1s capacidad para manejarlos de manera efectiva.<\/p>\n<p><strong>Esos desaf\u00edos pueden ser problemas &#8220;cotidianos&#8221;, como insolvencias de clientes y problemas de la cadena de suministro,<\/strong> o, como se ha visto en los \u00faltimos meses, eventos de &#8220;cisne negro&#8221; como la pandemia de COVID-19.<\/p>\n<p>Aunque la COVID-19 ha cambiado el mundo tal como lo conocemos, muchos de los desaf\u00edos habituales siguen siendo los mismos, pero potenciados. Y aunque pueden haber empeorado a corto plazo, seguir\u00e1n estando presentes una vez que la pandemia se haya retirado.<\/p>\n<p>La encuesta <em>El l\u00edder financiero del ma\u00f1ana<\/em>, elaborada por Euler Hermes, <a href=\"https:\/\/www.solunion.es\/lider-financiero-del-manana\/\" target=\"_blank\" rel=\"noopener\">a la que tienes acceso en este enlace&nbsp;<\/a> arroja luz sobre algunos de los desaf\u00edos que enfrenta la funci\u00f3n financiera y revela cu\u00e1les son las mayores preocupaciones.<\/p>\n<p><\/p>\n<h2>El riesgo de impago representa la mayor amenaza<\/h2>\n<p>La encuesta recoge testimonios de antes y despu\u00e9s de la pandemia. En ambas ocasiones, las respuestas muestran que <strong>las demoras en los pagos de los clientes son, con diferencia, el elemento m\u00e1s urgente en las agendas de los l\u00edderes financieros<\/strong>, por delante de otras preocupaciones como los ataques cibern\u00e9ticos y una disminuci\u00f3n en el volumen de ventas.<\/p>\n<ul>\n<li>Antes de la COVID-19, <strong>el 47% de los encuestados, en empresas de todos los tama\u00f1os, identificaban los retrasos en los pagos como un riesgo<\/strong> que hab\u00eda afectado a su negocio el a\u00f1o anterior. Cuando se le pregunt\u00f3 nuevamente en mayo qu\u00e9 riesgos hab\u00edan tenido un impacto en los dos meses anteriores, la cifra de retrasos en los pagos aument\u00f3 al 65%, lo que la convirti\u00f3 en la principal preocupaci\u00f3n en ambas ocasiones.<\/li>\n<li>La confianza para hacer frente a la falta de pago tambi\u00e9n se vio afectada. <strong>Antes del brote, solo el 44% de las empresas dijo que se sent\u00eda &#8220;completamente preparada&#8221; para hacer frente a los incidentes de pago.<\/strong> Desde que comenz\u00f3 la pandemia, la cifra cay\u00f3 al 31%.<\/li>\n<\/ul>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-12554 size-large\" src=\"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/2.-como-afectaron-los-riesgos-a-las-empresas-1024x326.png\" alt=\"gr\u00e1fico sobre los riesgos de las empresas\" width=\"1024\" height=\"326\" srcset=\"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/2.-como-afectaron-los-riesgos-a-las-empresas-1024x326.png 1024w, https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/2.-como-afectaron-los-riesgos-a-las-empresas-300x95.png 300w, https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/2.-como-afectaron-los-riesgos-a-las-empresas-768x244.png 768w, https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/2.-como-afectaron-los-riesgos-a-las-empresas-1536x489.png 1536w, https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/2.-como-afectaron-los-riesgos-a-las-empresas-2048x652.png 2048w, https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/2.-como-afectaron-los-riesgos-a-las-empresas-1320x420.png 1320w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>El informe recoge las estrategias de los directores financieros para responder al riesgo de impago. Destacaron tres \u00e1reas clave:<\/p>\n<h2>Los directores financieros tienen que implementar rigurosas verificaciones de cr\u00e9dito de forma proactiva<\/h2>\n<p>Es vital asegurarse de que se mantenga un enfoque claro en lo b\u00e1sico: recibir el pago a tiempo y proteger el flujo de efectivo. Nunca ha sido m\u00e1s importante garantizar que se trabaje con anticipaci\u00f3n para mitigar el riesgo.<\/p>\n<p>Algunos consejos pr\u00e1cticos:<\/p>\n<ul>\n<li>Ejecutar una verificaci\u00f3n de cr\u00e9dito: esto solo deber\u00eda ser un punto de partida, en caso de que los detalles no est\u00e9n completamente actualizados.<\/li>\n<li>Verificar las referencias crediticias: si un cliente nuevo potencial ha ofrecido referencias crediticias, asegurarse de examinarlas a fondo, en caso de que no sean leg\u00edtimas.<\/li>\n<li>Control de insolvencia: \u00bfalguno de los directores de la empresa se declar\u00f3 en quiebra o dirigi\u00f3 una empresa insolvente en el pasado? \u00bfCu\u00e1les fueron las circunstancias?<\/li>\n<li>Solicitar estados financieros: para verificar elementos espec\u00edficos.<\/li>\n<\/ul>\n<h2>La diversificaci\u00f3n puede reducir el riesgo de impago&nbsp;<\/h2>\n<p>Los encuestados opinaron que las empresas con una amplia gama de tipos de productos, o que se encuentran en m\u00faltiples industrias, estar\u00e1n en la mejor posici\u00f3n para hacer frente a los principales riesgos en el futuro. Puede parecer un clich\u00e9, pero no tener todos los huevos en una canasta puede ofrecer una protecci\u00f3n valiosa contra el riesgo de impago.<\/p>\n<p>Del mismo modo, en general se consider\u00f3 que incluso aquellos con una gama de productos m\u00e1s peque\u00f1a deber\u00edan centrarse en la diversificaci\u00f3n en el n\u00famero y tipo de clientes. Cuantos m\u00e1s clientes tenga, mayor ser\u00e1 el riesgo de impago.<\/p>\n<p><\/p>\n<h2>El seguro de cr\u00e9dito puede proteger contra la falta de pago<\/h2>\n<p>Los directores financieros creen que los seguros ser\u00e1n, y deber\u00edan ser, m\u00e1s importantes.<strong> El seguro de cr\u00e9dito comercial, en particular, puede proteger a las empresas contra el riesgo de impago,<\/strong> tanto en el caso de impago como de mora prolongada.<\/p>\n<p>Con el seguro de cr\u00e9dito comercial implementado, el asegurado sabe que su negocio est\u00e1 protegido contra riesgos comerciales y pol\u00edticos que est\u00e1n fuera de su control y tiene la seguridad de que se le pagar\u00e1 el dinero que se le adeude.<\/p>\n<p>Pero no se trata simplemente de comprar un producto listo para usar. Los encuestados creen que es fundamental trabajar en estrecha colaboraci\u00f3n con proveedores de seguros de confianza para lograr el nivel de protecci\u00f3n m\u00e1s adecuado.<\/p>\n<p>Involucrar a los proveedores de seguros, para que tengan un mejor conocimiento, significa que los t\u00e9rminos ser\u00e1n m\u00e1s espec\u00edficos y la protecci\u00f3n de riesgos m\u00e1s completa.<\/p>\n<p><strong>Los problemas de pago, junto con las insolvencias de los clientes, est\u00e1n muy presentes en la mente de los directores financieros,<\/strong> y es probable que se acent\u00faen en el clima actual. Sin embargo, los l\u00edderes financieros audaces adoptar\u00e1n un enfoque proactivo para que sus negocios est\u00e9n protegidos contra eventos futuros.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b918828 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b918828\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;fada2ab&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c05aedf\" data-id=\"2c05aedf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27f74c08 elementor-widget elementor-widget-text-editor\" data-id=\"27f74c08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Accede a la encuesta El l\u00edder financiero del ma\u00f1ana\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-54641d83\" data-id=\"54641d83\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a4f2e90 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3a4f2e90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.solunion.es\/lider-financiero-del-manana\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descargar <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Como probablemente estar\u00edan de acuerdo la mayor\u00eda de los directores financieros, una funci\u00f3n financiera eficiente y sin fricciones se basa en una combinaci\u00f3n de m\u00faltiples factores, que incluyen liderazgo, tecnolog\u00eda, procesos, talento, experiencia y comunicaci\u00f3n. Operar a un nivel \u00f3ptimo significa que cuando surgen desaf\u00edos, la funci\u00f3n financiera tiene m\u00e1s capacidad para manejarlos de manera [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":12559,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-12551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 estrategias para mitigar el riesgo de impago - Solunion, Credit and Surety insurance<\/title>\n<meta name=\"description\" content=\"Descubre c\u00f3mo los directores financieros lidian con los impagos para proteger su negocio tanto antes como despu\u00e9s de la pandemia de COVID-19\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 estrategias para mitigar el riesgo de impago - Solunion, Credit and Surety insurance\" \/>\n<meta property=\"og:description\" content=\"Descubre c\u00f3mo los directores financieros lidian con los impagos para proteger su negocio tanto antes como despu\u00e9s de la pandemia de COVID-19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/\" \/>\n<meta property=\"og:site_name\" content=\"Solunion, Credit and Surety insurance\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-22T09:55:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-22T11:57:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/riesgo-de-impago-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1608\" \/>\n\t<meta property=\"og:image:height\" content=\"908\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Solunion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@carla@showerthinking.com\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solunion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/3-estrategias-para-mitigar-el-riesgo-de-impago\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/3-estrategias-para-mitigar-el-riesgo-de-impago\\\/\"},\"author\":{\"name\":\"Solunion\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\"},\"headline\":\"3 estrategias para mitigar el riesgo de impago\",\"datePublished\":\"2021-03-22T09:55:48+00:00\",\"dateModified\":\"2021-03-22T11:57:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/3-estrategias-para-mitigar-el-riesgo-de-impago\\\/\"},\"wordCount\":911,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/3-estrategias-para-mitigar-el-riesgo-de-impago\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/riesgo-de-impago-2.png\",\"articleSection\":[\"Empresas\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/solunion.com\\\/en\\\/3-estrategias-para-mitigar-el-riesgo-de-impago\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/3-estrategias-para-mitigar-el-riesgo-de-impago\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/3-estrategias-para-mitigar-el-riesgo-de-impago\\\/\",\"name\":\"3 estrategias para mitigar el riesgo de impago - Solunion, Credit and Surety insurance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/3-estrategias-para-mitigar-el-riesgo-de-impago\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/3-estrategias-para-mitigar-el-riesgo-de-impago\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/riesgo-de-impago-2.png\",\"datePublished\":\"2021-03-22T09:55:48+00:00\",\"dateModified\":\"2021-03-22T11:57:06+00:00\",\"description\":\"Descubre c\u00f3mo los directores financieros lidian con los impagos para proteger su negocio tanto antes como despu\u00e9s de la pandemia de COVID-19\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/3-estrategias-para-mitigar-el-riesgo-de-impago\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solunion.com\\\/en\\\/3-estrategias-para-mitigar-el-riesgo-de-impago\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/3-estrategias-para-mitigar-el-riesgo-de-impago\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/riesgo-de-impago-2.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/riesgo-de-impago-2.png\",\"width\":1608,\"height\":908,\"caption\":\"Solo el 44% de los directores financieros se considera plenamente preparado frente al riesgo de impago.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/3-estrategias-para-mitigar-el-riesgo-de-impago\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solunion.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 estrategias para mitigar el riesgo de impago\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"name\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"description\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"alternateName\":\"Solunion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solunion.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\",\"name\":\"Solunion\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"width\":350,\"height\":96,\"caption\":\"Solunion\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\",\"name\":\"Solunion\",\"description\":\"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/carla@showerthinking.com\"]},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 estrategias para mitigar el riesgo de impago - Solunion, Credit and Surety insurance","description":"Descubre c\u00f3mo los directores financieros lidian con los impagos para proteger su negocio tanto antes como despu\u00e9s de la pandemia de COVID-19","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/","og_locale":"en_US","og_type":"article","og_title":"3 estrategias para mitigar el riesgo de impago - Solunion, Credit and Surety insurance","og_description":"Descubre c\u00f3mo los directores financieros lidian con los impagos para proteger su negocio tanto antes como despu\u00e9s de la pandemia de COVID-19","og_url":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/","og_site_name":"Solunion, Credit and Surety insurance","article_published_time":"2021-03-22T09:55:48+00:00","article_modified_time":"2021-03-22T11:57:06+00:00","og_image":[{"width":1608,"height":908,"url":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/riesgo-de-impago-2.png","type":"image\/png"}],"author":"Solunion","twitter_card":"summary_large_image","twitter_creator":"@carla@showerthinking.com","twitter_misc":{"Written by":"Solunion","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/#article","isPartOf":{"@id":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/"},"author":{"name":"Solunion","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366"},"headline":"3 estrategias para mitigar el riesgo de impago","datePublished":"2021-03-22T09:55:48+00:00","dateModified":"2021-03-22T11:57:06+00:00","mainEntityOfPage":{"@id":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/"},"wordCount":911,"commentCount":0,"publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"image":{"@id":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/riesgo-de-impago-2.png","articleSection":["Empresas"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/","url":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/","name":"3 estrategias para mitigar el riesgo de impago - Solunion, Credit and Surety insurance","isPartOf":{"@id":"https:\/\/solunion.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/#primaryimage"},"image":{"@id":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/riesgo-de-impago-2.png","datePublished":"2021-03-22T09:55:48+00:00","dateModified":"2021-03-22T11:57:06+00:00","description":"Descubre c\u00f3mo los directores financieros lidian con los impagos para proteger su negocio tanto antes como despu\u00e9s de la pandemia de COVID-19","breadcrumb":{"@id":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/#primaryimage","url":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/riesgo-de-impago-2.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/03\/riesgo-de-impago-2.png","width":1608,"height":908,"caption":"Solo el 44% de los directores financieros se considera plenamente preparado frente al riesgo de impago."},{"@type":"BreadcrumbList","@id":"https:\/\/solunion.com\/en\/3-estrategias-para-mitigar-el-riesgo-de-impago\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solunion.com\/en\/"},{"@type":"ListItem","position":2,"name":"3 estrategias para mitigar el riesgo de impago"}]},{"@type":"WebSite","@id":"https:\/\/solunion.com\/en\/#website","url":"https:\/\/solunion.com\/en\/","name":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","description":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"alternateName":"Solunion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solunion.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/solunion.com\/en\/#organization","name":"Solunion","url":"https:\/\/solunion.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","width":350,"height":96,"caption":"Solunion"},"image":{"@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366","name":"Solunion","description":"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.","sameAs":["https:\/\/x.com\/carla@showerthinking.com"]},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/12551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/comments?post=12551"}],"version-history":[{"count":0,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/12551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media\/12559"}],"wp:attachment":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media?parent=12551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/categories?post=12551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/tags?post=12551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}