{"id":12769,"date":"2021-06-17T10:27:21","date_gmt":"2021-06-17T08:27:21","guid":{"rendered":"https:\/\/solunion.com\/?p=12769"},"modified":"2021-06-28T17:32:06","modified_gmt":"2021-06-28T15:32:06","slug":"que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa","status":"publish","type":"post","link":"https:\/\/solunion.com\/en\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa\/","title":{"rendered":"\u00bfQu\u00e9 es People Analytics y c\u00f3mo puedes comenzar con un proyecto de People Analytics en tu empresa?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"12769\" class=\"elementor elementor-12769\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62eaa30b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62eaa30b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;a2e018c&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44b38d05\" data-id=\"44b38d05\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f4575a elementor-widget elementor-widget-text-editor\" data-id=\"6f4575a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si trabajas o tienes relaci\u00f3n con \u00e1reas de Personas\/Recursos Humanos, seguro que no es la primera vez que escuchas el t\u00e9rmino \u2018People Analytics\u2019 o \u2018HR Analytics\u2019.<\/p><p>Y es que no es para menos, puesto que cada vez son m\u00e1s las empresas y profesionales que suman People Analytics a sus funciones, algunas incluso sin ser conscientes de ello.<\/p><p>Pero \u00bfqu\u00e9 es People Analytics y c\u00f3mo puedes comenzar con un proyecto de People Analytics en tu empresa?<\/p><p>El \u00e1rea de Personas ya es, sin duda, una de las protagonistas clave de las organizaciones, y es que cada vez las empresas son m\u00e1s conscientes de la importancia que tiene, no solo centrarse en el cliente para lograr el \u00e9xito, sino tambi\u00e9n en el empleado\/a. Los retos del \u00e1rea nos ayudar\u00e1n cada vez m\u00e1s a conseguir poner en el centro a las personas y adem\u00e1s ser una palanca importante dentro de la estrategia de las compa\u00f1\u00edas.<\/p><p><strong>People Analytics consiste en llevar a cabo una serie de t\u00e9cnicas, cada vez m\u00e1s variadas, entre las que podemos destacar la estad\u00edstica (tanto descriptiva como inferencial), Business Intelligence y Big Dat<\/strong>a, que, con el apoyo de la tecnolog\u00eda, nos ayudar\u00e1n a realizar an\u00e1lisis para dar soluci\u00f3n a retos de diferente \u00edndole que surgen desde el \u00e1rea de Personas, y as\u00ed tomar decisiones. Los retos son muy variados, podemos nombrar algunos como la diversidad, la equidad retributiva, la rotaci\u00f3n, el absentismo o el an\u00e1lisis de relaciones.<\/p><p>Aparte de estas pr\u00e1cticas m\u00e1s avanzadas, el \u00e1rea de Personas se presenta ante una gran demanda de reporte de datos cada vez m\u00e1s creciente, que se concentra especialmente en los primeros meses del a\u00f1o. Y es que cada vez son m\u00e1s los reguladores e iniciativas que nos solicitan datos, y en algunos casos, lejos del mero reporte, las empresas debemos aportar, por normativa, ejercicios de an\u00e1lisis y c\u00e1lculos avanzados.<\/p><p><strong>Se puede aplicar People Analytics en empresas de cualquier tama\u00f1o y tipolog\u00eda, no siendo algo exclusivo de grandes multinacionales. <\/strong>Puedes pensar que se necesitan muchos datos, herramientas y\/o un gran equipo para poder desarrollar estas t\u00e9cnicas en tu empresa, pero esto est\u00e1 empezando a distar bastante de la realidad. La ambici\u00f3n y las ganas por \u2018querer hacer\u2019 en este caso te impulsar\u00e1n a conseguir dar respuesta a retos de una forma innovadora y pr\u00e1ctica.<\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-12772\" src=\"https:\/\/solunion.com\/wp-content\/uploads\/2021\/06\/ana-blazquez-people-analytics-en-solunion.png\" alt=\"Imagen de Ana Blazquez con una cita: People Analytics es aplicable a empresas de todos los tama\u00f1os. Las ganas de querer hacer son lo m\u00e1s importante.\" width=\"700\" height=\"430\" srcset=\"https:\/\/solunion.com\/wp-content\/uploads\/2021\/06\/ana-blazquez-people-analytics-en-solunion.png 1083w, https:\/\/solunion.com\/wp-content\/uploads\/2021\/06\/ana-blazquez-people-analytics-en-solunion-300x184.png 300w, https:\/\/solunion.com\/wp-content\/uploads\/2021\/06\/ana-blazquez-people-analytics-en-solunion-1024x630.png 1024w, https:\/\/solunion.com\/wp-content\/uploads\/2021\/06\/ana-blazquez-people-analytics-en-solunion-768x472.png 768w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/p><h2><strong>Algunos consejos para poder empezar un proyecto de People Analytics en tu empresa<\/strong><\/h2><p>Para empezar con un proyecto desde cero, estas son algunas de las consideraciones clave que te recomendamos tener en cuenta:<\/p><ul><li><strong>Comienza a asumir peque\u00f1os desaf\u00edos. Los an\u00e1lisis pueden comenzar con retos peque\u00f1os y r\u00e1pidos que est\u00e9n a tu alcance.<\/strong> La cantidad de informaci\u00f3n que se puede deducir de conjuntos de datos medianos es sorprendente. Si, por ejemplo, tu empresa tiene un gran volumen de absentismo y quieres analizar sus causas, puedes empezar dando respuesta a preguntas como: \u00bfen qu\u00e9 meses se ausentan m\u00e1s mis empleados? \u00bflas personas que m\u00e1s se ausentan tienen caracter\u00edsticas en com\u00fan?<\/li><li><strong>Instaura y promueve la cultura del dato<\/strong>. Los departamentos de Personas tienen su origen tradicionalmente en tareas administrativas. Ayuda a tus compa\u00f1ero\/as a entender la importancia de los datos, ens\u00e9\u00f1ales a interpretar datos mediante visualizaciones sencillas y hazles part\u00edcipes de los retos aprovechando su conocimiento sobre la materia.<\/li><li><strong>Une anal\u00edtica e intuici\u00f3n.<\/strong> Una de las caracter\u00edsticas de los profesionales de Personas es que tienen un sexto sentido para entender a los colaboradores y el porqu\u00e9 de las cosas. La intuici\u00f3n no es suficiente para explicar o predecir sucesos, pero los datos s\u00ed. La uni\u00f3n de intuici\u00f3n y anal\u00edtica es muy potente, haz uso de ella.<\/li><li><strong>Aprovecha las herramientas digitales. <\/strong>Trata de estar actualizado\/a en las herramientas y tecnolog\u00edas clave. Cada vez son m\u00e1s las herramientas que tenemos a nuestro alcance por un bajo coste, y cada vez se simplifica m\u00e1s su uso. No necesitas ser un experto o experta en tecnolog\u00eda o bases de datos. Potencia tu creatividad para exprimir al m\u00e1ximo las herramientas que est\u00e9n en tu mano.<\/li><li><strong>Sigue las tendencias. <\/strong>Las redes sociales est\u00e1n repletas de comunidades, profesionales e informaci\u00f3n en los que te puedes apoyar. Sigue a estos profesionales, \u00fanete a sus iniciativas, asiste a las charlas o webinars que se imparten de forma gratuita.<\/li><li>Y lo m\u00e1s importante, <strong>no tengas miedo.<\/strong> S\u00e9 ambicioso y ten la confianza de que puedes hacerlo. Conf\u00eda en que puedes empezar con los recursos de los que dispongas y l\u00e1nzate a la piscina.<\/li><\/ul><p>Este art\u00edculo ha sido redactado por <a href=\"https:\/\/www.linkedin.com\/in\/anablazquezcarvajal\/\" target=\"_blank\" rel=\"noopener\">Ana Bl\u00e1zquez Carvajal,<\/a> People Analytics en Solunion, y fue publicado originalmente en <a href=\"https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html\" target=\"_blank\" rel=\"noopener\">observatoriorh.com.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Si trabajas o tienes relaci\u00f3n con \u00e1reas de Personas\/Recursos Humanos, seguro que no es la primera vez que escuchas el t\u00e9rmino \u2018People Analytics\u2019 o \u2018HR Analytics\u2019. Y es que no es para menos, puesto que cada vez son m\u00e1s las empresas y profesionales que suman People Analytics a sus funciones, algunas incluso sin ser conscientes [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":12770,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[306,16],"tags":[550,551,385],"class_list":["post-12769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gentesolunion","category-empresas","tag-people-analytics","tag-personas","tag-recursos-humanos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 es People Analytics y c\u00f3mo puedes comenzar con un proyecto de People Analytics en tu empresa? - Solunion, Credit and Surety insurance<\/title>\n<meta name=\"description\" content=\"Aprende qu\u00e9 es People Analytics y c\u00f3mo comenzar con un proyecto de este tipo en tu compa\u00f1\u00eda, con estos consejos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es People Analytics y c\u00f3mo puedes comenzar con un proyecto de People Analytics en tu empresa? - Solunion, Credit and Surety insurance\" \/>\n<meta property=\"og:description\" content=\"Aprende qu\u00e9 es People Analytics y c\u00f3mo comenzar con un proyecto de este tipo en tu compa\u00f1\u00eda, con estos consejos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html\" \/>\n<meta property=\"og:site_name\" content=\"Solunion, Credit and Surety insurance\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-17T08:27:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-28T15:32:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solunion.com\/wp-content\/uploads\/2021\/06\/que-es-people-analytics.png\" \/>\n\t<meta property=\"og:image:width\" content=\"867\" \/>\n\t<meta property=\"og:image:height\" content=\"489\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Solunion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@carla@showerthinking.com\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solunion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.observatoriorh.com\\\/opinion\\\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa\\\/\"},\"author\":{\"name\":\"Solunion\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\"},\"headline\":\"\u00bfQu\u00e9 es People Analytics y c\u00f3mo puedes comenzar con un proyecto de People Analytics en tu empresa?\",\"datePublished\":\"2021-06-17T08:27:21+00:00\",\"dateModified\":\"2021-06-28T15:32:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa\\\/\"},\"wordCount\":839,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.observatoriorh.com\\\/opinion\\\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/que-es-people-analytics.png\",\"keywords\":[\"people analytics\",\"personas\",\"recursos humanos\"],\"articleSection\":[\"#GenteSolunion\",\"Empresas\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.observatoriorh.com\\\/opinion\\\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa\\\/\",\"url\":\"https:\\\/\\\/www.observatoriorh.com\\\/opinion\\\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html\",\"name\":\"\u00bfQu\u00e9 es People Analytics y c\u00f3mo puedes comenzar con un proyecto de People Analytics en tu empresa? - Solunion, Credit and Surety insurance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.observatoriorh.com\\\/opinion\\\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.observatoriorh.com\\\/opinion\\\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/que-es-people-analytics.png\",\"datePublished\":\"2021-06-17T08:27:21+00:00\",\"dateModified\":\"2021-06-28T15:32:06+00:00\",\"description\":\"Aprende qu\u00e9 es People Analytics y c\u00f3mo comenzar con un proyecto de este tipo en tu compa\u00f1\u00eda, con estos consejos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.observatoriorh.com\\\/opinion\\\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.observatoriorh.com\\\/opinion\\\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.observatoriorh.com\\\/opinion\\\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#primaryimage\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/que-es-people-analytics.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/que-es-people-analytics.png\",\"width\":867,\"height\":489},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.observatoriorh.com\\\/opinion\\\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solunion.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es People Analytics y c\u00f3mo puedes comenzar con un proyecto de People Analytics en tu empresa?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"name\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"description\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"alternateName\":\"Solunion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solunion.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\",\"name\":\"Solunion\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"width\":350,\"height\":96,\"caption\":\"Solunion\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\",\"name\":\"Solunion\",\"description\":\"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/carla@showerthinking.com\"]},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es People Analytics y c\u00f3mo puedes comenzar con un proyecto de People Analytics en tu empresa? - Solunion, Credit and Surety insurance","description":"Aprende qu\u00e9 es People Analytics y c\u00f3mo comenzar con un proyecto de este tipo en tu compa\u00f1\u00eda, con estos consejos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html","og_locale":"en_US","og_type":"article","og_title":"\u00bfQu\u00e9 es People Analytics y c\u00f3mo puedes comenzar con un proyecto de People Analytics en tu empresa? - Solunion, Credit and Surety insurance","og_description":"Aprende qu\u00e9 es People Analytics y c\u00f3mo comenzar con un proyecto de este tipo en tu compa\u00f1\u00eda, con estos consejos","og_url":"https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html","og_site_name":"Solunion, Credit and Surety insurance","article_published_time":"2021-06-17T08:27:21+00:00","article_modified_time":"2021-06-28T15:32:06+00:00","og_image":[{"width":867,"height":489,"url":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/06\/que-es-people-analytics.png","type":"image\/png"}],"author":"Solunion","twitter_card":"summary_large_image","twitter_creator":"@carla@showerthinking.com","twitter_misc":{"Written by":"Solunion","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#article","isPartOf":{"@id":"https:\/\/solunion.com\/en\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa\/"},"author":{"name":"Solunion","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366"},"headline":"\u00bfQu\u00e9 es People Analytics y c\u00f3mo puedes comenzar con un proyecto de People Analytics en tu empresa?","datePublished":"2021-06-17T08:27:21+00:00","dateModified":"2021-06-28T15:32:06+00:00","mainEntityOfPage":{"@id":"https:\/\/solunion.com\/en\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa\/"},"wordCount":839,"commentCount":0,"publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"image":{"@id":"https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/06\/que-es-people-analytics.png","keywords":["people analytics","personas","recursos humanos"],"articleSection":["#GenteSolunion","Empresas"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/solunion.com\/en\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa\/","url":"https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html","name":"\u00bfQu\u00e9 es People Analytics y c\u00f3mo puedes comenzar con un proyecto de People Analytics en tu empresa? - Solunion, Credit and Surety insurance","isPartOf":{"@id":"https:\/\/solunion.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#primaryimage"},"image":{"@id":"https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/06\/que-es-people-analytics.png","datePublished":"2021-06-17T08:27:21+00:00","dateModified":"2021-06-28T15:32:06+00:00","description":"Aprende qu\u00e9 es People Analytics y c\u00f3mo comenzar con un proyecto de este tipo en tu compa\u00f1\u00eda, con estos consejos","breadcrumb":{"@id":"https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#primaryimage","url":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/06\/que-es-people-analytics.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2021\/06\/que-es-people-analytics.png","width":867,"height":489},{"@type":"BreadcrumbList","@id":"https:\/\/www.observatoriorh.com\/opinion\/que-es-people-analytics-y-como-puedes-comenzar-con-un-proyecto-de-people-analytics-en-tu-empresa.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solunion.com\/en\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es People Analytics y c\u00f3mo puedes comenzar con un proyecto de People Analytics en tu empresa?"}]},{"@type":"WebSite","@id":"https:\/\/solunion.com\/en\/#website","url":"https:\/\/solunion.com\/en\/","name":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","description":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"alternateName":"Solunion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solunion.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/solunion.com\/en\/#organization","name":"Solunion","url":"https:\/\/solunion.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","width":350,"height":96,"caption":"Solunion"},"image":{"@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366","name":"Solunion","description":"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.","sameAs":["https:\/\/x.com\/carla@showerthinking.com"]},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/12769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/comments?post=12769"}],"version-history":[{"count":0,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/12769\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media\/12770"}],"wp:attachment":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media?parent=12769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/categories?post=12769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/tags?post=12769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}