{"id":18248,"date":"2025-07-14T11:28:16","date_gmt":"2025-07-14T09:28:16","guid":{"rendered":"https:\/\/solunion.com\/?p=18248"},"modified":"2025-07-14T11:28:16","modified_gmt":"2025-07-14T09:28:16","slug":"entrevista-a-jose-medina-solis-director-financiero-de-imedexa","status":"publish","type":"post","link":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/","title":{"rendered":"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"18248\" class=\"elementor elementor-18248\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8207c82 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8207c82\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b39b4e\" data-id=\"3b39b4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07644f7 elementor-widget elementor-widget-text-editor\" data-id=\"07644f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Desde sus inicios en los a\u00f1os 90, Imedexa ha evolucionado de una peque\u00f1a empresa en Casar de C\u00e1ceres a un referente internacional en el dise\u00f1o y fabricaci\u00f3n de estructuras met\u00e1licas para uso el\u00e9ctrico. En esta entrevista, su Director Financiero, Jos\u00e9 Medina Sol\u00eds, repasa los hitos de esta transformaci\u00f3n, destacando el papel clave del seguro de cr\u00e9dito y del corredor en su estrategia de crecimiento y gesti\u00f3n del riesgo comercial.\u00a0<\/p><p>Con presencia en 52 pa\u00edses y una plantilla de 700 personas, Imedexa ha basado su expansi\u00f3n en tres pilares: la mejora continua del conocimiento t\u00e9cnico, la incorporaci\u00f3n de tecnolog\u00eda puntera y la diversificaci\u00f3n internacional. Esta \u00faltima representa hoy el 78% de su negocio, con proyectos emblem\u00e1ticos como el tren Medina-La Meca, la Torre atirantada de Leipzig o la evacuaci\u00f3n de la central del lago Victoria en Kenia.<\/p><p>La gesti\u00f3n del riesgo comercial es un factor determinante para la compa\u00f1\u00eda. \u201c<em>La p\u00e9rdida de un solo cliente puede tener un impacto muy fuerte en la cuenta de resultados<\/em>\u201d, afirma Medina. Por ello,\u00a0 apuestan por herramientas que le permitan anticiparse y tomar decisiones informadas, como el seguro de cr\u00e9dito y la p\u00f3liza de medio plazo recientemente incorporada.<\/p><p>La relaci\u00f3n con Solunion, que ya suma dos d\u00e9cadas, ha sido clave en este proceso. \u201c<em>La decisi\u00f3n de atender a un cliente se basa en m\u00e1s de un 90% en las nociones que te traslade tu compa\u00f1\u00eda de seguros<\/em>\u201d, explica.\u00a0<\/p><p>En este contexto, la figura del corredor cobra una relevancia estrat\u00e9gica. \u201c<em>La importancia es muy alta. Le est\u00e1s dando una llave muy importante de tu negocio para el futuro<\/em>\u201d, se\u00f1ala Medina. El corredor no solo facilita respuestas r\u00e1pidas para la toma de decisiones, sino que tambi\u00e9n adapta la p\u00f3liza a las necesidades espec\u00edficas de cada operaci\u00f3n, actuando como un socio activo y flexible.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4a4b9740 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4a4b9740\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;_id&quot;:&quot;fada2ab&quot;,&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34126582\" data-id=\"34126582\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41259b48 elementor-widget elementor-widget-heading\" data-id=\"41259b48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">LEE LA ENTREVISTA COMPLETA<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b8d2d88 elementor-widget elementor-widget-text-editor\" data-id=\"5b8d2d88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/solunion.com\/wp-content\/uploads\/2025\/07\/Entrevista_Imedexa.pdf\"><span style=\"text-decoration: underline;\"><span style=\"font-weight: 400;\"><span style=\"color: #bb9dc7;\">Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa<\/span><\/span><\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Desde sus inicios en los a\u00f1os 90, Imedexa ha evolucionado de una peque\u00f1a empresa en Casar de C\u00e1ceres a un referente internacional en el dise\u00f1o y fabricaci\u00f3n de estructuras met\u00e1licas para uso el\u00e9ctrico. En esta entrevista, su Director Financiero, Jos\u00e9 Medina Sol\u00eds, repasa los hitos de esta transformaci\u00f3n, destacando el papel clave del seguro de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":18249,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-18248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-empresas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa - Solunion, Credit and Surety insurance<\/title>\n<meta name=\"description\" content=\"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa, que repasa la trayectoria de la compa\u00f1\u00eda, sus desaf\u00edos y sus planes de futuro\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa - Solunion, Credit and Surety insurance\" \/>\n<meta property=\"og:description\" content=\"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa, que repasa la trayectoria de la compa\u00f1\u00eda, sus desaf\u00edos y sus planes de futuro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/\" \/>\n<meta property=\"og:site_name\" content=\"Solunion, Credit and Surety insurance\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-14T09:28:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solunion.com\/wp-content\/uploads\/2025\/07\/web-entrevista-imedexa-solunion.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Solunion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@carla@showerthinking.com\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solunion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\\\/\"},\"author\":{\"name\":\"Solunion\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\"},\"headline\":\"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa\",\"datePublished\":\"2025-07-14T09:28:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\\\/\"},\"wordCount\":352,\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/web-entrevista-imedexa-solunion.png\",\"articleSection\":[\"Empresas\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\\\/\",\"name\":\"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa - Solunion, Credit and Surety insurance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/web-entrevista-imedexa-solunion.png\",\"datePublished\":\"2025-07-14T09:28:16+00:00\",\"description\":\"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa, que repasa la trayectoria de la compa\u00f1\u00eda, sus desaf\u00edos y sus planes de futuro\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solunion.com\\\/en\\\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/web-entrevista-imedexa-solunion.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/web-entrevista-imedexa-solunion.png\",\"width\":900,\"height\":508,\"caption\":\"Jose Medina Sol\u00eds, Director Financiero de Imedexa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solunion.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"name\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"description\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"alternateName\":\"Solunion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solunion.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\",\"name\":\"Solunion\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"width\":350,\"height\":96,\"caption\":\"Solunion\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/9b915c29b4248a4155758bce80926366\",\"name\":\"Solunion\",\"description\":\"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/carla@showerthinking.com\"]},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa - Solunion, Credit and Surety insurance","description":"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa, que repasa la trayectoria de la compa\u00f1\u00eda, sus desaf\u00edos y sus planes de futuro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/","og_locale":"en_US","og_type":"article","og_title":"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa - Solunion, Credit and Surety insurance","og_description":"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa, que repasa la trayectoria de la compa\u00f1\u00eda, sus desaf\u00edos y sus planes de futuro","og_url":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/","og_site_name":"Solunion, Credit and Surety insurance","article_published_time":"2025-07-14T09:28:16+00:00","og_image":[{"width":900,"height":508,"url":"https:\/\/solunion.com\/wp-content\/uploads\/2025\/07\/web-entrevista-imedexa-solunion.png","type":"image\/png"}],"author":"Solunion","twitter_card":"summary_large_image","twitter_creator":"@carla@showerthinking.com","twitter_misc":{"Written by":"Solunion","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/#article","isPartOf":{"@id":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/"},"author":{"name":"Solunion","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366"},"headline":"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa","datePublished":"2025-07-14T09:28:16+00:00","mainEntityOfPage":{"@id":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/"},"wordCount":352,"publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"image":{"@id":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2025\/07\/web-entrevista-imedexa-solunion.png","articleSection":["Empresas"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/","url":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/","name":"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa - Solunion, Credit and Surety insurance","isPartOf":{"@id":"https:\/\/solunion.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/#primaryimage"},"image":{"@id":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2025\/07\/web-entrevista-imedexa-solunion.png","datePublished":"2025-07-14T09:28:16+00:00","description":"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa, que repasa la trayectoria de la compa\u00f1\u00eda, sus desaf\u00edos y sus planes de futuro","breadcrumb":{"@id":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/#primaryimage","url":"https:\/\/solunion.com\/wp-content\/uploads\/2025\/07\/web-entrevista-imedexa-solunion.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2025\/07\/web-entrevista-imedexa-solunion.png","width":900,"height":508,"caption":"Jose Medina Sol\u00eds, Director Financiero de Imedexa"},{"@type":"BreadcrumbList","@id":"https:\/\/solunion.com\/en\/entrevista-a-jose-medina-solis-director-financiero-de-imedexa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solunion.com\/en\/"},{"@type":"ListItem","position":2,"name":"Entrevista a Jos\u00e9 Medina Sol\u00eds, Director Financiero de Imedexa"}]},{"@type":"WebSite","@id":"https:\/\/solunion.com\/en\/#website","url":"https:\/\/solunion.com\/en\/","name":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","description":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"alternateName":"Solunion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solunion.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/solunion.com\/en\/#organization","name":"Solunion","url":"https:\/\/solunion.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","width":350,"height":96,"caption":"Solunion"},"image":{"@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/9b915c29b4248a4155758bce80926366","name":"Solunion","description":"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.","sameAs":["https:\/\/x.com\/carla@showerthinking.com"]},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/18248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/comments?post=18248"}],"version-history":[{"count":5,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/18248\/revisions"}],"predecessor-version":[{"id":18258,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/18248\/revisions\/18258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media\/18249"}],"wp:attachment":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media?parent=18248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/categories?post=18248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/tags?post=18248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}