{"id":9002,"date":"2019-05-29T09:00:54","date_gmt":"2019-05-29T07:00:54","guid":{"rendered":"https:\/\/solunion.com\/?p=9002"},"modified":"2019-11-27T09:36:49","modified_gmt":"2019-11-27T08:36:49","slug":"los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea","status":"publish","type":"post","link":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/","title":{"rendered":"Los retos de la industria del autom\u00f3vil ante la nueva regulaci\u00f3n de emisiones de CO2 de la Uni\u00f3n Europea"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"9002\" class=\"elementor elementor-9002\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d7efdc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d7efdc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;1ebf73a&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0950551\" data-id=\"0950551\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5035504 elementor-widget elementor-widget-text-editor\" data-id=\"5035504\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El principal reto para la industria automovil\u00edstica Europeo no reside en el Brexit o en las posibles tarifas de Estados Unidos, sino en la propia regulaci\u00f3n de la UE para la limitaci\u00f3n de las emisiones de di\u00f3xido de carbono.<\/p><p>Los objetivos marcados podr\u00edan conducir a un escenario complicado para el sector, con desaf\u00edos industriales, financieros y comerciales en paralelo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-60588e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"60588e3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;1ebf73a&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-218fc3d\" data-id=\"218fc3d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1232d8a elementor-widget elementor-widget-text-editor\" data-id=\"1232d8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/solunion.com\/\">Solunion,<\/a> la compa\u00f1\u00eda experta en seguros de cr\u00e9dito y de cauci\u00f3n y en servicios de gesti\u00f3n del cr\u00e9dito comercial, analiza los \u00faltimos datos de uno de sus accionistas, Euler Hermes, sobre el sector del autom\u00f3vil, en relaci\u00f3n a los nuevos objetivos de la Uni\u00f3n Europea para la reducci\u00f3n de las emisiones de CO2.<\/p><p>El reto m\u00e1s importante para la industria automovil\u00edstica no es el Brexit o la posibilidad de que Estados Unidos endurezca su pol\u00edtica proteccionista con m\u00e1s aranceles. El principal desaf\u00edo reside en el propio reglamento de la Uni\u00f3n Europea para limitar las emisiones de di\u00f3xido de carbono.<\/p><p>El 15 de abril de 2019, tras varias rondas de reuniones, los representantes de la Comisi\u00f3n Europea, el Consejo Europeo y el Parlamento Europeo, acordaron reducir las emisiones medias de CO2 de los nuevos turismos un 15% en 2025 y un 37,5% en 2030, en l\u00ednea con los objetivos internacionales establecidos en el Acuerdo de Par\u00eds COP21.<\/p><p>La aplicaci\u00f3n de estos objetivos a la industria del autom\u00f3vil supone tres grandes retos:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d72db71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d72db71\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;1ebf73a&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13b1352\" data-id=\"13b1352\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d333162 elementor-widget elementor-widget-text-editor\" data-id=\"d333162\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Uno, de <strong>car\u00e1cter industrial<\/strong>, en la medida en que estas metas requerir\u00e1n un ajuste dr\u00e1stico de la producci\u00f3n en favor de veh\u00edculos de combustible alternativo, especialmente los el\u00e9ctricos. La cuota de mercado de estos veh\u00edculos de combustible alternativo deber\u00eda sobrepasar el 25% para cumplir con la regulaci\u00f3n europea, independientemente de las cuotas de mercado de las combinaciones de gasolina y di\u00e9sel.<\/p><p>El segundo reto ser\u00eda el Si tomamos como referencia los datos de 2018, el total de penalizaciones podr\u00eda alcanzar los 30.000 millones de euros para el panel observado de fabricantes de autom\u00f3viles, casi todos ellos involucrados en el mercado europeo, y de los cuales, ninguno ha alcanzado a\u00fan el objetivo de CO2 de 2021. Esta cantidad representa casi el 18% del EBITDA combinado y pr\u00e1cticamente la mitad (45%) de sus ganancias netas combinadas registradas en 2018 (67.000 millones de euros). Adem\u00e1s, el ajuste industrial mencionado en el punto anterior, requerido para alcanzar el objetivo, implicar\u00e1 un aumento importante de los costes de producci\u00f3n (+7% en 2020 de media).<\/p><p>Por \u00faltimo, destaca el <strong>reto comercial<\/strong>. La repercusi\u00f3n del total de costes adicionales de producci\u00f3n a los clientes, conducir\u00eda a una disminuci\u00f3n del -9% en las ventas de veh\u00edculos para finales de 2020 y del -28% para 2025. La ca\u00edda recortar\u00eda 0,1 pp al crecimiento de Francia y Alemania en 2019 y 2020, y la creciente competencia de fabricantes de veh\u00edculos el\u00e9ctricos a\u00f1adir\u00eda presi\u00f3n a los m\u00e1rgenes y a la facturaci\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7352b48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7352b48\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;1ebf73a&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a7ddbc5\" data-id=\"a7ddbc5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28b9efa elementor-widget elementor-widget-text-editor\" data-id=\"28b9efa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los fabricantes de coches tendr\u00e1n que esforzarse para superar estos retos mediante el uso de los buffers de capital acumulados y la reducci\u00f3n de costes, el aprovechamiento de los \u201csupercr\u00e9ditos\u201d y la entrada en acuerdos de asociaci\u00f3n llamados \u201cpools\u201d. Esta estrategia de adaptaci\u00f3n parcial, les permitir\u00e1 cumplir con el 30% de sus obligaciones. Como resultado, para finales de 2020 se espera una subida de +2,6% en los precios medios de los coches, una disminuci\u00f3n de -3,1% de las nuevas matriculaciones y una p\u00e9rdida de 2900 millones en ventas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e3698b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e3698b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;fada2ab&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;}],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-19eb9ac\" data-id=\"19eb9ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-200db06 elementor-widget elementor-widget-text-editor\" data-id=\"200db06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNP_Los retos de la industria del autom\u00f3vil.pdf\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bb82410\" data-id=\"bb82410\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6559a9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d6559a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/solunion.com\/wp-content\/uploads\/2019\/10\/NP_Los-retos-de-la-industria-del-autom\u00f3vil.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-file-pdf\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Descargar nota de prensa<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>El principal reto para la industria automovil\u00edstica Europeo no reside en el Brexit o en las posibles tarifas de Estados Unidos, sino en la propia regulaci\u00f3n de la UE para la limitaci\u00f3n de las emisiones de di\u00f3xido de carbono. Los objetivos marcados podr\u00edan conducir a un escenario complicado para el sector, con desaf\u00edos industriales, financieros [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9004,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"categories":[13],"tags":[],"class_list":["post-9002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sectores"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los retos de la industria del autom\u00f3vil ante la nueva regulaci\u00f3n de emisiones de CO2 de la Uni\u00f3n Europea - Solunion, Credit and Surety insurance<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los retos de la industria del autom\u00f3vil ante la nueva regulaci\u00f3n de emisiones de CO2 de la Uni\u00f3n Europea - Solunion, Credit and Surety insurance\" \/>\n<meta property=\"og:description\" content=\"El principal reto para la industria automovil\u00edstica Europeo no reside en el Brexit o en las posibles tarifas de Estados Unidos, sino en la propia regulaci\u00f3n de la UE para la limitaci\u00f3n de las emisiones de di\u00f3xido de carbono. Los objetivos marcados podr\u00edan conducir a un escenario complicado para el sector, con desaf\u00edos industriales, financieros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/\" \/>\n<meta property=\"og:site_name\" content=\"Solunion, Credit and Surety insurance\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-29T07:00:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-27T08:36:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solunion.com\/wp-content\/uploads\/2019\/10\/retos-de-la-industria-del-automovil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"508\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Solunion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Solunion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\\\/\"},\"author\":{\"name\":\"Solunion\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/ded98238991d8e1f9742bb54f5a26909\"},\"headline\":\"Los retos de la industria del autom\u00f3vil ante la nueva regulaci\u00f3n de emisiones de CO2 de la Uni\u00f3n Europea\",\"datePublished\":\"2019-05-29T07:00:54+00:00\",\"dateModified\":\"2019-11-27T08:36:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\\\/\"},\"wordCount\":633,\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/retos-de-la-industria-del-automovil.jpg\",\"articleSection\":[\"Sectores\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\\\/\",\"name\":\"Los retos de la industria del autom\u00f3vil ante la nueva regulaci\u00f3n de emisiones de CO2 de la Uni\u00f3n Europea - Solunion, Credit and Surety insurance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/retos-de-la-industria-del-automovil.jpg\",\"datePublished\":\"2019-05-29T07:00:54+00:00\",\"dateModified\":\"2019-11-27T08:36:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solunion.com\\\/en\\\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/retos-de-la-industria-del-automovil.jpg\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/retos-de-la-industria-del-automovil.jpg\",\"width\":900,\"height\":508,\"caption\":\"Los retos de la industria del autom\u00f3vil ante la nueva regulaci\u00f3n de emisiones de CO2 de la Uni\u00f3n Europea\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solunion.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los retos de la industria del autom\u00f3vil ante la nueva regulaci\u00f3n de emisiones de CO2 de la Uni\u00f3n Europea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"name\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"description\":\"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n\",\"publisher\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\"},\"alternateName\":\"Solunion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solunion.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#organization\",\"name\":\"Solunion\",\"url\":\"https:\\\/\\\/solunion.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"contentUrl\":\"https:\\\/\\\/solunion.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo-solunion.png\",\"width\":350,\"height\":96,\"caption\":\"Solunion\"},\"image\":{\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solunion.com\\\/en\\\/#\\\/schema\\\/person\\\/ded98238991d8e1f9742bb54f5a26909\",\"name\":\"Solunion\",\"description\":\"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial.\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los retos de la industria del autom\u00f3vil ante la nueva regulaci\u00f3n de emisiones de CO2 de la Uni\u00f3n Europea - Solunion, Credit and Surety insurance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/","og_locale":"en_US","og_type":"article","og_title":"Los retos de la industria del autom\u00f3vil ante la nueva regulaci\u00f3n de emisiones de CO2 de la Uni\u00f3n Europea - Solunion, Credit and Surety insurance","og_description":"El principal reto para la industria automovil\u00edstica Europeo no reside en el Brexit o en las posibles tarifas de Estados Unidos, sino en la propia regulaci\u00f3n de la UE para la limitaci\u00f3n de las emisiones de di\u00f3xido de carbono. Los objetivos marcados podr\u00edan conducir a un escenario complicado para el sector, con desaf\u00edos industriales, financieros [&hellip;]","og_url":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/","og_site_name":"Solunion, Credit and Surety insurance","article_published_time":"2019-05-29T07:00:54+00:00","article_modified_time":"2019-11-27T08:36:49+00:00","og_image":[{"width":900,"height":508,"url":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/10\/retos-de-la-industria-del-automovil.jpg","type":"image\/jpeg"}],"author":"Solunion","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Solunion","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/#article","isPartOf":{"@id":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/"},"author":{"name":"Solunion","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/ded98238991d8e1f9742bb54f5a26909"},"headline":"Los retos de la industria del autom\u00f3vil ante la nueva regulaci\u00f3n de emisiones de CO2 de la Uni\u00f3n Europea","datePublished":"2019-05-29T07:00:54+00:00","dateModified":"2019-11-27T08:36:49+00:00","mainEntityOfPage":{"@id":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/"},"wordCount":633,"publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"image":{"@id":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/10\/retos-de-la-industria-del-automovil.jpg","articleSection":["Sectores"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/","url":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/","name":"Los retos de la industria del autom\u00f3vil ante la nueva regulaci\u00f3n de emisiones de CO2 de la Uni\u00f3n Europea - Solunion, Credit and Surety insurance","isPartOf":{"@id":"https:\/\/solunion.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/#primaryimage"},"image":{"@id":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/#primaryimage"},"thumbnailUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/10\/retos-de-la-industria-del-automovil.jpg","datePublished":"2019-05-29T07:00:54+00:00","dateModified":"2019-11-27T08:36:49+00:00","breadcrumb":{"@id":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/#primaryimage","url":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/10\/retos-de-la-industria-del-automovil.jpg","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/10\/retos-de-la-industria-del-automovil.jpg","width":900,"height":508,"caption":"Los retos de la industria del autom\u00f3vil ante la nueva regulaci\u00f3n de emisiones de CO2 de la Uni\u00f3n Europea"},{"@type":"BreadcrumbList","@id":"https:\/\/solunion.com\/en\/los-retos-de-la-industria-del-automovil-ante-la-nueva-regulacion-de-emisiones-de-co2-de-la-union-europea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solunion.com\/en\/"},{"@type":"ListItem","position":2,"name":"Los retos de la industria del autom\u00f3vil ante la nueva regulaci\u00f3n de emisiones de CO2 de la Uni\u00f3n Europea"}]},{"@type":"WebSite","@id":"https:\/\/solunion.com\/en\/#website","url":"https:\/\/solunion.com\/en\/","name":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","description":"Solunion, seguros de Cr\u00e9dito y de Cauci\u00f3n","publisher":{"@id":"https:\/\/solunion.com\/en\/#organization"},"alternateName":"Solunion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solunion.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/solunion.com\/en\/#organization","name":"Solunion","url":"https:\/\/solunion.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","contentUrl":"https:\/\/solunion.com\/wp-content\/uploads\/2019\/09\/logo-solunion.png","width":350,"height":96,"caption":"Solunion"},"image":{"@id":"https:\/\/solunion.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/solunion.com\/en\/#\/schema\/person\/ded98238991d8e1f9742bb54f5a26909","name":"Solunion","description":"Somos impulso. Somos expertos en seguros de Cr\u00e9dito y de Cauci\u00f3n, servicio de Recobro, y otros asociados a la gesti\u00f3n del riesgo comercial."},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/9002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/comments?post=9002"}],"version-history":[{"count":0,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/posts\/9002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media\/9004"}],"wp:attachment":[{"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/media?parent=9002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/categories?post=9002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solunion.com\/en\/wp-json\/wp\/v2\/tags?post=9002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}